{"id":2610,"date":"2023-01-27T17:52:21","date_gmt":"2023-01-27T15:52:21","guid":{"rendered":"https:\/\/www.neptune.gr\/accommodation\/meltemi-suite\/"},"modified":"2025-10-08T10:34:16","modified_gmt":"2025-10-08T07:34:16","slug":"meltemi-suite","status":"publish","type":"accommodation","link":"https:\/\/www.neptune.gr\/de\/accommodation\/meltemi-suite\/","title":{"rendered":"Meltemi Suite"},"excerpt":{"rendered":"<p>ca. 170 m\u00b2 | Belegung 2 &#8211; 4 G\u00e4ste<\/p>\n","protected":false},"featured_media":2199,"template":"","accommodation_type":[37],"class_list":["post-2610","accommodation","type-accommodation","status-publish","has-post-thumbnail","hentry","accommodation_type-suiten"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Meltemi Suite | Neptune Luxury Resort<\/title>\n<meta name=\"description\" content=\"Die Meltemi Suite befindet sich - nur ein paar Meter vom Meer entfernt - in der ersten Etage eines Bungalows und bietet einen gro\u00dfz\u00fcgigen, geschmackvoll ausgestatteten privaten Balkon mit atemberaubend sch\u00f6nem Blick auf die \u00c4g\u00e4is.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.neptune.gr\/de\/accommodation\/meltemi-suite\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Meltemi Suite | Neptune Luxury Resort\" \/>\n<meta property=\"og:description\" content=\"Die Meltemi Suite befindet sich - nur ein paar Meter vom Meer entfernt - in der ersten Etage eines Bungalows und bietet einen gro\u00dfz\u00fcgigen, geschmackvoll ausgestatteten privaten Balkon mit atemberaubend sch\u00f6nem Blick auf die \u00c4g\u00e4is.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.neptune.gr\/de\/accommodation\/meltemi-suite\/\" \/>\n<meta property=\"og:site_name\" content=\"Neptune Luxury Resort\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/NeptuneHotelsKos\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-08T07:34:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.neptune.gr\/wp-content\/uploads\/2023\/01\/neptunekos18432-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1100\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.neptune.gr\\\/de\\\/accommodation\\\/meltemi-suite\\\/\",\"url\":\"https:\\\/\\\/www.neptune.gr\\\/de\\\/accommodation\\\/meltemi-suite\\\/\",\"name\":\"Meltemi Suite | Neptune Luxury Resort\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.neptune.gr\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.neptune.gr\\\/de\\\/accommodation\\\/meltemi-suite\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.neptune.gr\\\/de\\\/accommodation\\\/meltemi-suite\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.neptune.gr\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/neptunekos18432-1.jpg\",\"datePublished\":\"2023-01-27T15:52:21+00:00\",\"dateModified\":\"2025-10-08T07:34:16+00:00\",\"description\":\"Die Meltemi Suite befindet sich - nur ein paar Meter vom Meer entfernt - in der ersten Etage eines Bungalows und bietet einen gro\u00dfz\u00fcgigen, geschmackvoll ausgestatteten privaten Balkon mit atemberaubend sch\u00f6nem Blick auf die \u00c4g\u00e4is.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.neptune.gr\\\/de\\\/accommodation\\\/meltemi-suite\\\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.neptune.gr\\\/de\\\/accommodation\\\/meltemi-suite\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/www.neptune.gr\\\/de\\\/accommodation\\\/meltemi-suite\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.neptune.gr\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/neptunekos18432-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.neptune.gr\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/neptunekos18432-1.jpg\",\"width\":1100,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.neptune.gr\\\/de\\\/accommodation\\\/meltemi-suite\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.neptune.gr\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Meltemi Suite\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.neptune.gr\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.neptune.gr\\\/de\\\/\",\"name\":\"Neptune Luxury Resort\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.neptune.gr\\\/de\\\/#organization\"},\"alternateName\":\"Neptune\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.neptune.gr\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.neptune.gr\\\/de\\\/#organization\",\"name\":\"Neptune Luxury Resort\",\"alternateName\":\"Neptune\",\"url\":\"https:\\\/\\\/www.neptune.gr\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/www.neptune.gr\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.neptune.gr\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/positive-logo-rgb-light.jpg\",\"contentUrl\":\"https:\\\/\\\/www.neptune.gr\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/positive-logo-rgb-light.jpg\",\"width\":775,\"height\":600,\"caption\":\"Neptune Luxury Resort\"},\"image\":{\"@id\":\"https:\\\/\\\/www.neptune.gr\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/NeptuneHotelsKos\\\/\",\"https:\\\/\\\/www.instagram.com\\\/neptunehotels\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/neptunehotelskos\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Meltemi Suite | Neptune Luxury Resort","description":"Die Meltemi Suite befindet sich - nur ein paar Meter vom Meer entfernt - in der ersten Etage eines Bungalows und bietet einen gro\u00dfz\u00fcgigen, geschmackvoll ausgestatteten privaten Balkon mit atemberaubend sch\u00f6nem Blick auf die \u00c4g\u00e4is.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.neptune.gr\/de\/accommodation\/meltemi-suite\/","og_locale":"de_DE","og_type":"article","og_title":"Meltemi Suite | Neptune Luxury Resort","og_description":"Die Meltemi Suite befindet sich - nur ein paar Meter vom Meer entfernt - in der ersten Etage eines Bungalows und bietet einen gro\u00dfz\u00fcgigen, geschmackvoll ausgestatteten privaten Balkon mit atemberaubend sch\u00f6nem Blick auf die \u00c4g\u00e4is.","og_url":"https:\/\/www.neptune.gr\/de\/accommodation\/meltemi-suite\/","og_site_name":"Neptune Luxury Resort","article_publisher":"https:\/\/www.facebook.com\/NeptuneHotelsKos\/","article_modified_time":"2025-10-08T07:34:16+00:00","og_image":[{"width":1100,"height":600,"url":"https:\/\/www.neptune.gr\/wp-content\/uploads\/2023\/01\/neptunekos18432-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.neptune.gr\/de\/accommodation\/meltemi-suite\/","url":"https:\/\/www.neptune.gr\/de\/accommodation\/meltemi-suite\/","name":"Meltemi Suite | Neptune Luxury Resort","isPartOf":{"@id":"https:\/\/www.neptune.gr\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.neptune.gr\/de\/accommodation\/meltemi-suite\/#primaryimage"},"image":{"@id":"https:\/\/www.neptune.gr\/de\/accommodation\/meltemi-suite\/#primaryimage"},"thumbnailUrl":"https:\/\/www.neptune.gr\/wp-content\/uploads\/2023\/01\/neptunekos18432-1.jpg","datePublished":"2023-01-27T15:52:21+00:00","dateModified":"2025-10-08T07:34:16+00:00","description":"Die Meltemi Suite befindet sich - nur ein paar Meter vom Meer entfernt - in der ersten Etage eines Bungalows und bietet einen gro\u00dfz\u00fcgigen, geschmackvoll ausgestatteten privaten Balkon mit atemberaubend sch\u00f6nem Blick auf die \u00c4g\u00e4is.","breadcrumb":{"@id":"https:\/\/www.neptune.gr\/de\/accommodation\/meltemi-suite\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.neptune.gr\/de\/accommodation\/meltemi-suite\/"]}]},{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.neptune.gr\/de\/accommodation\/meltemi-suite\/#primaryimage","url":"https:\/\/www.neptune.gr\/wp-content\/uploads\/2023\/01\/neptunekos18432-1.jpg","contentUrl":"https:\/\/www.neptune.gr\/wp-content\/uploads\/2023\/01\/neptunekos18432-1.jpg","width":1100,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/www.neptune.gr\/de\/accommodation\/meltemi-suite\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.neptune.gr\/de\/"},{"@type":"ListItem","position":2,"name":"Meltemi Suite"}]},{"@type":"WebSite","@id":"https:\/\/www.neptune.gr\/de\/#website","url":"https:\/\/www.neptune.gr\/de\/","name":"Neptune Luxury Resort","description":"","publisher":{"@id":"https:\/\/www.neptune.gr\/de\/#organization"},"alternateName":"Neptune","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.neptune.gr\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Organization","@id":"https:\/\/www.neptune.gr\/de\/#organization","name":"Neptune Luxury Resort","alternateName":"Neptune","url":"https:\/\/www.neptune.gr\/de\/","logo":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.neptune.gr\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.neptune.gr\/wp-content\/uploads\/2023\/04\/positive-logo-rgb-light.jpg","contentUrl":"https:\/\/www.neptune.gr\/wp-content\/uploads\/2023\/04\/positive-logo-rgb-light.jpg","width":775,"height":600,"caption":"Neptune Luxury Resort"},"image":{"@id":"https:\/\/www.neptune.gr\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/NeptuneHotelsKos\/","https:\/\/www.instagram.com\/neptunehotels\/","https:\/\/www.linkedin.com\/company\/neptunehotelskos\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.neptune.gr\/de\/wp-json\/wp\/v2\/accommodation\/2610","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.neptune.gr\/de\/wp-json\/wp\/v2\/accommodation"}],"about":[{"href":"https:\/\/www.neptune.gr\/de\/wp-json\/wp\/v2\/types\/accommodation"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.neptune.gr\/de\/wp-json\/wp\/v2\/media\/2199"}],"wp:attachment":[{"href":"https:\/\/www.neptune.gr\/de\/wp-json\/wp\/v2\/media?parent=2610"}],"wp:term":[{"taxonomy":"accommodation_type","embeddable":true,"href":"https:\/\/www.neptune.gr\/de\/wp-json\/wp\/v2\/accommodation_type?post=2610"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}